{"id":6141,"date":"2023-03-08T16:02:28","date_gmt":"2023-03-08T15:02:28","guid":{"rendered":"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173.jpg"},"modified":"2023-05-22T10:29:00","modified_gmt":"2023-05-22T08:29:00","slug":"ghirardelli-iveco-0fh7173-2","status":"inherit","type":"attachment","link":"https:\/\/www.giemghirardelli.it\/en\/home-2\/ghirardelli-iveco-0fh7173-2\/","title":{"rendered":"Ghirardelli-Iveco-0FH7173"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-6141","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-300x200.jpg 300w, https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-1024x683.jpg 1024w, https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-768x512.jpg 768w, https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-1536x1025.jpg 1536w, https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-2048x1366.jpg 2048w, https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-1320x881.jpg 1320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2100,"height":1401,"file":"2023\/03\/Ghirardelli-Iveco-0FH7173.jpg","filesize":316024,"sizes":{"medium":{"file":"Ghirardelli-Iveco-0FH7173-300x200.jpg","width":300,"height":200,"filesize":15982,"mime_type":"image\/jpeg","source_url":"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-300x200.jpg"},"large":{"file":"Ghirardelli-Iveco-0FH7173-1024x683.jpg","width":1024,"height":683,"filesize":120909,"mime_type":"image\/jpeg","source_url":"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-1024x683.jpg"},"thumbnail":{"file":"Ghirardelli-Iveco-0FH7173-150x150.jpg","width":150,"height":150,"filesize":7407,"mime_type":"image\/jpeg","source_url":"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-150x150.jpg"},"medium_large":{"file":"Ghirardelli-Iveco-0FH7173-768x512.jpg","width":768,"height":512,"filesize":74784,"mime_type":"image\/jpeg","source_url":"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-768x512.jpg"},"1536x1536":{"file":"Ghirardelli-Iveco-0FH7173-1536x1025.jpg","width":1536,"height":1025,"filesize":232912,"mime_type":"image\/jpeg","source_url":"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-1536x1025.jpg"},"2048x2048":{"file":"Ghirardelli-Iveco-0FH7173-2048x1366.jpg","width":2048,"height":1366,"filesize":364170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-2048x1366.jpg"},"mailpoet_newsletter_max":{"file":"Ghirardelli-Iveco-0FH7173-1320x881.jpg","width":1320,"height":881,"filesize":183133,"mime_type":"image\/jpeg","source_url":"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173-1320x881.jpg"},"full":{"file":"Ghirardelli-Iveco-0FH7173.jpg","width":2100,"height":1401,"mime_type":"image\/jpeg","source_url":"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"FH","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":7007,"source_url":"https:\/\/www.giemghirardelli.it\/wp-content\/uploads\/2023\/03\/Ghirardelli-Iveco-0FH7173.jpg","_links":{"self":[{"href":"https:\/\/www.giemghirardelli.it\/en\/wp-json\/wp\/v2\/media\/6141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.giemghirardelli.it\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.giemghirardelli.it\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.giemghirardelli.it\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.giemghirardelli.it\/en\/wp-json\/wp\/v2\/comments?post=6141"}]}}